{"id":9009,"date":"2024-11-07T15:48:59","date_gmt":"2024-11-07T06:48:59","guid":{"rendered":"http:\/\/kir931726.kir.jp\/blog\/?post_type=crossmarche-article&#038;p=9009"},"modified":"2024-11-14T15:24:07","modified_gmt":"2024-11-14T06:24:07","slug":"241115_cf_cardigan","status":"publish","type":"crossmarche-article","link":"http:\/\/kir931726.kir.jp\/blog\/crossmarche-article\/241115_cf_cardigan\/","title":{"rendered":"241115_cf_cardigan"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-9009","crossmarche-article","type-crossmarche-article","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/crossmarche-article\/9009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/crossmarche-article"}],"about":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/types\/crossmarche-article"}],"wp:attachment":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/media?parent=9009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}