{"id":6989,"date":"2024-05-01T16:07:28","date_gmt":"2024-05-01T07:07:28","guid":{"rendered":"http:\/\/kir931726.kir.jp\/blog\/?post_type=crossmarche-article&#038;p=6989"},"modified":"2025-02-27T10:52:33","modified_gmt":"2025-02-27T01:52:33","slug":"water-bottle","status":"publish","type":"crossmarche-article","link":"http:\/\/kir931726.kir.jp\/blog\/crossmarche-article\/water-bottle\/","title":{"rendered":"water-bottle"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-6989","crossmarche-article","type-crossmarche-article","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/crossmarche-article\/6989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/crossmarche-article"}],"about":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/types\/crossmarche-article"}],"wp:attachment":[{"href":"http:\/\/kir931726.kir.jp\/blog\/wp-json\/wp\/v2\/media?parent=6989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}